{"id":2773,"date":"2024-02-19T07:15:36","date_gmt":"2024-02-19T07:15:36","guid":{"rendered":"https:\/\/cambodiaip.aditidemo.asia\/?page_id=2773"},"modified":"2024-05-28T16:15:14","modified_gmt":"2024-05-28T16:15:14","slug":"what-are-layout-designstopographies-of-integrated-circuits","status":"publish","type":"page","link":"http:\/\/www.cambodiaip.gov.kh\/en\/what-are-layout-designstopographies-of-integrated-circuits\/","title":{"rendered":"What Are Layout Designs(Topographies) Of Integrated Circuits?"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2773\" class=\"elementor elementor-2773\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e95f522 e-con-full e-flex e-con e-parent\" data-id=\"e95f522\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5cca67c e-con-full e-flex e-con e-child\" data-id=\"5cca67c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fac1d94 elementor-widget elementor-widget-wp-widget-nav_menu\" data-id=\"fac1d94\" data-element_type=\"widget\" data-widget_type=\"wp-widget-nav_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"menu-introduction-ip-menu-container\"><ul id=\"menu-introduction-ip-menu\" class=\"menu\"><li id=\"menu-item-3439\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3439\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-intellectual-property\/\">What Is Intellectual Property?<\/a><\/li>\n<li id=\"menu-item-3438\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3438\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-benefit-of-ip\/\">What Is Benefit Of IP?<\/a><\/li>\n<li id=\"menu-item-3440\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3440\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-ip-for-business\/\">What IP For Business?<\/a><\/li>\n<li id=\"menu-item-3441\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3441\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-a-trademark\/\">What Is A Trademark?<\/a><\/li>\n<li id=\"menu-item-3442\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3442\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-trade-name\/\">What Is Trade Name?<\/a><\/li>\n<li id=\"menu-item-3443\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3443\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-a-patent\/\">What Is A Patent?<\/a><\/li>\n<li id=\"menu-item-3444\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3444\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-an-industrial-design\/\">What Is An Industrial Design?<\/a><\/li>\n<li id=\"menu-item-3445\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3445\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-a-utility-model\/\">What Is A Utility Model?<\/a><\/li>\n<li id=\"menu-item-3446\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3446\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-a-plant-variety-protection\/\">What Is A Plant Variety Protection?<\/a><\/li>\n<li id=\"menu-item-3447\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3447\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-are-copyright-and-related-rights\/\">What Are Copyright And Related Rights?<\/a><\/li>\n<li id=\"menu-item-3448\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3448\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-a-geographical-indication\/\">What Is A Geographical Indication?<\/a><\/li>\n<li id=\"menu-item-3449\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3449\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-trade-secret\/\">What Is Trade Secret?<\/a><\/li>\n<li id=\"menu-item-3450\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3450\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-undisclosed-information\/\">What Is Undisclosed Information?<\/a><\/li>\n<li id=\"menu-item-3451\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3451\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-are-layout-designstopographies-of-integrated-circuits\/\">What Are Layout Designs(Topographies) Of Integrated Circuits?<\/a><\/li>\n<li id=\"menu-item-3452\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3452\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-are-traditional-knowledge-and-genetic-resource\/\">What Are Traditional Knowledge And Genetic Resource?<\/a><\/li>\n<li id=\"menu-item-3453\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3453\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-an-act-of-unfair-competition\/\">What Is An Act Of Unfair Competition?<\/a><\/li>\n<li id=\"menu-item-3454\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3454\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/what-is-compulsory-licensing-for-public-health\/\">What Is Compulsory Licensing For Public Health?<\/a><\/li>\n<li id=\"menu-item-3455\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3455\"><a href=\"http:\/\/www.cambodiaip.gov.kh\/en\/ip-as-marketing-tool\/\">IP As Marketing Tool<\/a><\/li>\n<\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-546d87c e-con-full e-flex e-con e-child\" data-id=\"546d87c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3bd44c2 elementor-widget elementor-widget-heading\" data-id=\"3bd44c2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">What Are Layout Designs(Topographies) Of Integrated Circuits?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-451be60 elementor-widget elementor-widget-wp-widget-text\" data-id=\"451be60\" data-element_type=\"widget\" data-widget_type=\"wp-widget-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"textwidget\"><div class=\"elementor elementor-2769\" data-elementor-type=\"wp-page\" data-elementor-id=\"2769\">\n<div class=\"elementor-element elementor-element-2de6002 e-con-full e-flex e-con e-parent\" data-id=\"2de6002\" data-element_type=\"container\" data-core-v316-plus=\"true\">\n<div class=\"elementor-element elementor-element-a33b97c e-con-full e-flex e-con e-child\" data-id=\"a33b97c\" data-element_type=\"container\">\n<div class=\"elementor-element elementor-element-855a013 elementor-widget elementor-widget-wp-widget-text\" data-id=\"855a013\" data-element_type=\"widget\" data-widget_type=\"wp-widget-text.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"textwidget\">\n<p>\u17a2\u178f\u17d2\u1790\u1794\u1791\u1780\u17c6\u1796\u17bb\u1784\u1780\u17c2\u179f\u1798\u17d2\u179a\u17bd\u179b\u17d4<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>What Are Layout Designs(Topographies) Of Integrated Circuits?<\/p>","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-2773","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"http:\/\/www.cambodiaip.gov.kh\/en\/wp-json\/wp\/v2\/pages\/2773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.cambodiaip.gov.kh\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.cambodiaip.gov.kh\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.cambodiaip.gov.kh\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.cambodiaip.gov.kh\/en\/wp-json\/wp\/v2\/comments?post=2773"}],"version-history":[{"count":14,"href":"http:\/\/www.cambodiaip.gov.kh\/en\/wp-json\/wp\/v2\/pages\/2773\/revisions"}],"predecessor-version":[{"id":6202,"href":"http:\/\/www.cambodiaip.gov.kh\/en\/wp-json\/wp\/v2\/pages\/2773\/revisions\/6202"}],"wp:attachment":[{"href":"http:\/\/www.cambodiaip.gov.kh\/en\/wp-json\/wp\/v2\/media?parent=2773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}